{"id":3160,"count":17,"description":"","link":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/","name":"Hahnem\u00fchle calendar competition","slug":"hahnemuehle-calendar-competition","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/\" \/>\n<meta property=\"og:site_name\" content=\"Hahnem\u00fchle Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/tag\\\/hahnemuehle-calendar-competition\\\/\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/tag\\\/hahnemuehle-calendar-competition\\\/\",\"name\":\"Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/tag\\\/hahnemuehle-calendar-competition\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/tag\\\/hahnemuehle-calendar-competition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hahnem\u00fchle calendar competition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/\",\"name\":\"Hahnem\u00fchle Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/","og_locale":"en_GB","og_type":"article","og_title":"Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog","og_url":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/","og_site_name":"Hahnem\u00fchle Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/","url":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/","name":"Hahnem\u00fchle calendar competition Archive - Hahnem\u00fchle Blog","isPartOf":{"@id":"https:\/\/blog.hahnemuehle.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hahnemuehle.com\/en\/tag\/hahnemuehle-calendar-competition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.hahnemuehle.com\/en\/"},{"@type":"ListItem","position":2,"name":"Hahnem\u00fchle calendar competition"}]},{"@type":"WebSite","@id":"https:\/\/blog.hahnemuehle.com\/en\/#website","url":"https:\/\/blog.hahnemuehle.com\/en\/","name":"Hahnem\u00fchle Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hahnemuehle.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blog.hahnemuehle.com\/en\/wp-json\/wp\/v2\/tags\/3160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hahnemuehle.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.hahnemuehle.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.hahnemuehle.com\/en\/wp-json\/wp\/v2\/posts?tags=3160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}