{"id":17065,"date":"2019-02-18T17:09:17","date_gmt":"2019-02-18T16:09:17","guid":{"rendered":"https:\/\/blog.hahnemuehle.com\/fr\/?p=17065"},"modified":"2019-06-25T15:10:16","modified_gmt":"2019-06-25T13:10:16","slug":"compte-rebours-concours-photo-etudiant","status":"publish","type":"post","link":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/","title":{"rendered":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 !"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<span class=\"tlid-translation translation\"><span class=\"\" title=\"\">Le tout premier <a href=\"https:\/\/www.hahnemuehle.com\/en\/digital-fineart\/student-photo-competition.html\">concours photo \u00e9tudiant<\/a> Hahnem\u00fchle d\u00e9marre tr\u00e8s bient\u00f4t, au mois de mars et nous commencerons par l&rsquo;\u00e9tape de soumissions des images. Vous en \u00eates ? Relevez le d\u00e9fi et rencontrez notre jury !\u00a0<\/span><\/span><\/p>\n<p>A l&rsquo;occasion de notre concours photo \u00e9tudiant, nous avons r\u00e9uni un jury de renomm\u00e9e internationale qui \u00e9valuera vos photos d&rsquo;un oeil professionnel. Notre jury, compos\u00e9 de photographes, journalistes photo, galeristes et experts du monde de la photographie, \u00e9valuera les s\u00e9ries de photos selon les crit\u00e8res suivants :<\/p>\n<p>\u2013 qualit\u00e9 artistique \u2013 composition, cr\u00e9ativit\u00e9 et force de persuasion visuelle<\/p>\n<p>\u2013 qualit\u00e9 technique \u2013 mise en oeuvre technique\/pratique<\/p>\n<p>\u2013 qualit\u00e9 du contenu \u2013 relation entre le concept et la force de persuasion<\/p>\n<p>Participez au concours, impressionnez le jury par votre travail et votre cr\u00e9ativit\u00e9 !\u00a0<span class=\"tlid-translation translation\"><br \/>\n<span class=\"\" title=\"\">Nous allons vous pr\u00e9senter d\u00e8s \u00e0 pr\u00e9sent et sur les semaines \u00e0 venir les diff\u00e9rents membres du jury.<\/span><\/span><\/p>\n<p><span class=\"tlid-translation translation\"><span class=\"\" title=\"\">C&rsquo;est parti !<\/span><\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<a href=\"http:\/\/www.rolfnobel.de\/\" target=\"_blank\" rel=\"noopener\">Rolf Nobel<\/a>\u00a0est professeur de photographie \u00e0 l&rsquo;Universit\u00e9 des Sciences Appliqu\u00e9es de Hambourg et \u00e0 l&rsquo;Universit\u00e9 des Sciences Appliqu\u00e9es de Hannovre, dans lesquelles il a jou\u00e9 un r\u00f4le essentiel dans la cr\u00e9ation des cours de photojournalisme et photographie documentaire. Il a contribu\u00e9 \u00e0 transformer le programme en l&rsquo;un des plus grands d&rsquo;Allemagne et l&rsquo;une des plus talentueuses acad\u00e9mies de photojournalisme au monde.<\/p>\n<p>Tout en travaillant sur ses propres projets photographiques et de livres, Rolf Nobel anime des ateliers de photojournalisme, photographie urbaine et photographie de voyage pour l&rsquo;Union de Journalistes Allemands, l&rsquo;Institut ver.di et l&rsquo;Agence de Presse Allemande (dpa), entre autres. Il est aussi membre de jurys, par exemple \u00e0 la Photo de l&rsquo;Ann\u00e9e UNICEF, le Prix de Photographie Alfred Fried, le prix VGH et le concours Presse Photo Bayern.<\/p>\n<p>Rolf Nobel est co-fondateur de l&rsquo;association de photographie FreeLens et membre du conseil administratif. Il est aussi fondateur et directeur du Festival Lumix pour la Jeune photo journalisme \u00e0 Hannovre et directeur de la galerie photo GAF, \u00e9galement \u00e0 Hannovre.<\/p>\n<p>En 2016, l&rsquo;Association de Photo Allemande a r\u00e9compens\u00e9 Rolf Nobel avec le prix du Dr Erich Salomon, un des plus prestigieux prix de photographie en Allemagne.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb17068&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb17069&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<a class=\"external-link-new-window\" title=\"\u00d6ffnet externen Link in neuem Fenster\" href=\"http:\/\/www.c4fap.org\/about-us\/\" target=\"_blank\" rel=\"noopener\">Hamidah Glasgow<\/a>\u00a0a \u00e9t\u00e9 la Directrice Ex\u00e9cutive et curatrice du The Center for Fine Art Photography \u00e0 Fort Collins, Colorado depuis 2009. Hamidah est dipl\u00f4m\u00e9e d&rsquo;un master en sciences humaines avec une sp\u00e9cialisation dans les \u00e9tudes visuelles et de genre et est \u00e9galement dipl\u00f4m\u00e9e en philosophie.<\/p>\n<p>La contribution de Hamidah \u00e0 la photographie inclue des projets de curation, des revues de portfolio nationaux (FotoFest, Photolucida, Medium, Center, Filter, etc.), la participation \u00e0 des publications et de magazines en ligne.<\/p>\n<p>Elle a re\u00e7u en 2018 le prix Gould Vision in Photography et est co-fondatrice du collectif Strange Fire. Ce collectif est d\u00e9di\u00e9 aux travaux \u00e0 base de photographie qui enr\u00f4le les forces politiques et sociales, soulignant le travail des femmes, les personnes de couleurs, les artistes transgenre et travestis, \u00e9crivains et curateurs.<\/p>\n<p>Hamidah \u2013 (prononc\u00e9 Ha-me-dah) s&rsquo;int\u00e9resse \u00e0 des projets tr\u00e8s vari\u00e9s allant de travaux finis, projets en construction et brain storming. Hamidah peut vous aider sur l&rsquo;\u00e9dition, le s\u00e9quen\u00e7age et le d\u00e9veloppement de projets. Elle recherche des artistes du monde de la photo pour des expositions et fonctionnalit\u00e9s web. Elle ne s&rsquo;int\u00e9resse pas aux nus traditionnels, paysages communs et travaux commerciaux.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<a class=\"external-link-new-window\" title=\"\u00d6ffnet externen Link in neuem Fenster\" href=\"http:\/\/www.zeldacheatle.com\/\" target=\"_blank\" rel=\"noopener\">Zelda Cheatle<\/a>\u00a0est une curatrice et \u00e9ditrice renomm\u00e9e dans le monde de la photographie. Apr\u00e8s quelques ann\u00e9es pass\u00e9es \u00e0 faire elle-m\u00eame de la photo, elle a commenc\u00e9 une carri\u00e8re de galeriste \u00e0 la\u00a0<a href=\"https:\/\/thephotographersgallery.org.uk\/\" target=\"_blank\" rel=\"noopener\">Photographers Gallery<\/a>\u00a0de London de 1982 \u00e0 1988, travaillant avec des photographes mondialement connus et des artistes \u00e9mergents anglais et europ\u00e9ens utilisant la photographie dans leurs travaux.<\/p>\n<p>De 1989 \u00e0 2005, l&rsquo;\u00e9ponyme Zelda Cheatle Gallery a expos\u00e9 les travaux de jeunes artistes illustres et \u00e9mergents, qui exprimaient aussi l&rsquo;importance de l&rsquo;histoire de la photographie tout au long du 20\u00e8 si\u00e8cle. De 2005 \u00e0 2012, Zelda Cheatle a \u00e9t\u00e9 \u00e0 l&rsquo;initiative du premier Photography Fund, de sa cr\u00e9ation et de son animation.<\/p>\n<p>R\u00e9unissant principalement des tirages d&rsquo;art du 20\u00e8 si\u00e8cle, la collection \u00ab\u00a0Fund Collection\u00a0\u00bb comptait les archives de Eve Eve Arnold, des tirages vintage et une collection russe importante de Rodchenko \u00e0 Lissitzky et de l&rsquo;\u00e9cole Vhutemas, et une collection iconique du 20\u00e8 si\u00e8cle de Sudek \u00e0 Steichen. Aujourd&rsquo;hui, Zelda recherche des images, \u00e9tudie et acquiert des photographies du monde entier.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb17072&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb17070&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<a class=\"external-link-new-window\" title=\"\u00d6ffnet externen Link in neuem Fenster\" href=\"http:\/\/www.alfabetizacaovisual.com.br\/\" target=\"_blank\" rel=\"noopener\">Jo\u00e3o Kulcs\u00e1r<\/a>\u00a0est dipl\u00f4m\u00e9 de l&rsquo;Universit\u00e9 du Kent en Angleterre. Il enseignait \u00e9galement \u00e0 l&rsquo;Universit\u00e9 de Harvard. Professeur et coordinateur de photographie \u00e0 l&rsquo;Universit\u00e9 de Senac. Pr\u00e9sident de REDE, un r\u00e9seau de producteurs de photographie au Br\u00e9sil.<\/p>\n<p>Curateur d&rsquo;exposition sur la photo au Br\u00e9sil comme Claudia Andujar, Yanomami, Maureen Bisilliat, Bolivia, Thomaz Farkas \u201cr\u00e9trospective\u201d, Lewis Hine \u201cLes photographes am\u00e9riciains de la FSA\u201d, \u201cles 60 ans de Magnum\u201d, Edward Curtis \u201cPortrait\u201d, \u201cObservateurs, photographes de la sc\u00e8ne anglaise depuis 1930 \u00e0 nos jours\u201d, \u201cPortrait d&rsquo;Immigrant\u201d Ellis Island, Arno Rafael Minkkinen \u201cL&rsquo;\u00e9vidence du corps\u201d, \u201cMagnum : portraits de cin\u00e9ma , dialogues et identit\u00e9\u201d, Henri Cartier-Bresson \u201cLes premiers photographes\u201d et Elliott Erwitt \u201cVie de chien\u201d.<\/p>\n<p>Il est \u00e9galement auteur de livres comme Heran\u00e7a Compartilhada; \u00c1rvores da Cidade de S\u00e3o Paulo; Impress\u00f5es Visuais; Observadores da Cena Brit\u00e2nica; Viva o Brasil; Retratos Imigrantes;\u00a0Acervo do MIS-SP ( Mem\u00f3ria Paulistana; Lambe-lambe, fot\u00f3grafos de rua nos anos 70; e Ferrovia Madeira-Mamor\u00e9)et \u00e9diteur de site internet.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]N\u00e9 en Allemagne en 1958, <a class=\"external-link-new-window\" title=\"\u00d6ffnet externen Link in neuem Fenster\" href=\"https:\/\/www.joachimschmeisser.com\/\" target=\"_blank\" rel=\"noopener\">Joachim Schmeisser<\/a>\u00a0est plus connu pour ses s\u00e9ries de photographies prises en Afrique de l&rsquo;Est, un portrait iconique d&rsquo;\u00e9l\u00e9phants, et plus pr\u00e9cis\u00e9ment des \u00e9l\u00e9phants orphelins de la Sheldrick Wildlife Trust au Kenya.<\/p>\n<p>Il a d\u00e9marr\u00e9 un projet en 2009 \u2013 lors d&rsquo;une halte \u00e0 la montagne des gorilles au Rwanda et chez les Hadzabe, des chasseurs-cueilleurs, de Tanzanie. Tout a chang\u00e9 lorsqu&rsquo;il s&rsquo;est retrouv\u00e9 entour\u00e9 de ces b\u00e9b\u00e9s \u00e9l\u00e9phants et sa halte s&rsquo;est transform\u00e9e en une amiti\u00e9 extraordinaire et un projet fantastique. Ce projet existe toujours aujourd&rsquo;hui et est devenu une cause ch\u00e8re \u00e0 son coeur.<\/p>\n<p>En 2012, Joachim Schmeisser a gagn\u00e9 le prestigieux prix Hasselblad pour son travail. En n 2017, son livre \u00bbElephants in Heaven\u00ab a \u00e9t\u00e9 \u00e9dit\u00e9 par l&rsquo;\u00e9diteur allemand teNeues et vendu jusqu&rsquo;\u00e0 \u00e9puisement des stocks en 4 mois.<\/p>\n<p>\u00bbJe sens que ce travail est pour moi un exemple sans pr\u00e9c\u00e9dent de la balance parfaite entre cr\u00e9er une ic\u00f4ne et travailler avec une ic\u00f4ne.\u00ab \u00e9crit l&rsquo;\u00e9diteur d&rsquo;art Fridey Mickel du TAZ Berlin au sujet de son travail et Matthias Harder, Curateur en Chef de la Fondation Helmut Newton de Berlin, en parle comme un homme de conviction avec une approche \u00e9cologique et visuelle. \u00bbIl donne quelque chose en retour \u00e0 cette terre et nous contamine avec son enthousiasme pour les \u00e9l\u00e9phants.\u00ab<\/p>\n<p>La volont\u00e9 de Joachim Schmeisser est de montrer la beaut\u00e9 et le caract\u00e8re unique de notre plan\u00e8te et de d\u00e9velopper notre sensibilit\u00e9 \u00e0 ces sujets qui nous concerne tous. Egalement, il d\u00e9tient la\u00a0<a href=\"http:\/\/www.immagis.de\/\" target=\"_blank\" rel=\"noopener\">FineArt Gallery immagis<\/a>\u00a0\u00e0 Munich et touche aussi \u00e0 la curation de photographie et l&rsquo;impression.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb17127&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17145\" src=\"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/03\/Kathrin_O3A8875-243x300.jpg\" alt=\"\" width=\"243\" height=\"300\" srcset=\"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/03\/Kathrin_O3A8875-243x300.jpg 243w, https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/03\/Kathrin_O3A8875-829x1024.jpg 829w, https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/03\/Kathrin_O3A8875.jpg 1913w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]Apr\u00e8s ses \u00e9tudes de Management des Affaires, Kathrin K\u00f6hler a travaill\u00e9 avec son partenaire, un photographe professionnel, dans la publicit\u00e9 et le design.<\/p>\n<p>En 2009, elle a cr\u00e9\u00e9 la galerie IMMAGIS en Allemagne et se sp\u00e9cialise dans l&rsquo;art photographique contemporain. IMMAGIS est synonyme d&rsquo;excellence, classe et extravagance dans la sc\u00e8ne photographique internationale, des photographes reconnus aux jeunes talents. IMMAGIS est situ\u00e9 dans le quartier du Mus\u00e9e de Munich. Plus d&rsquo;infos : \u00a0<a href=\"http:\/\/www.immagis.de\/\" target=\"_blank\" rel=\"noopener\">www.immagis.de<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Le tout premier concours photo \u00e9tudiant Hahnem\u00fchle d\u00e9marre tr\u00e8s bient\u00f4t, au mois de mars et nous commencerons par l&rsquo;\u00e9tape de soumissions des images. Vous en \u00eates ? Relevez le d\u00e9fi et rencontrez notre jury !\u00a0 A l&rsquo;occasion de notre concours photo \u00e9tudiant, nous avons r\u00e9uni un jury de renomm\u00e9e internationale qui \u00e9valuera vos photos d&rsquo;un&hellip;<\/p>\n","protected":false},"author":9,"featured_media":17106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1919],"tags":[3319],"class_list":["post-17065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-concours-photo-etudiant","category-1919","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Le tout premier concours photo \u00e9tudiant Hahnem\u00fchle d\u00e9marre tr\u00e8s bient\u00f4t, au mois de mars et nous commencerons par l&rsquo;\u00e9tape de soumissions des images. Vous en \u00eates ? Relevez le d\u00e9fi et rencontrez notre jury !\u00a0 A l&rsquo;occasion de notre concours photo \u00e9tudiant, nous avons r\u00e9uni un jury de renomm\u00e9e internationale qui \u00e9valuera vos photos d&rsquo;un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/\" \/>\n<meta property=\"og:site_name\" content=\"Hahnem\u00fchle Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T16:09:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-25T13:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1048\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bettina Scheerbarth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bettina Scheerbarth\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/\"},\"author\":{\"name\":\"Bettina Scheerbarth\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\"},\"headline\":\"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 !\",\"datePublished\":\"2019-02-18T16:09:17+00:00\",\"dateModified\":\"2019-06-25T13:10:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/\"},\"wordCount\":1482,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/02\\\/Fotowettbewerb-Blog_Header_Jury.jpg\",\"keywords\":[\"concours photo \u00e9tudiant\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/\",\"name\":\"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/02\\\/Fotowettbewerb-Blog_Header_Jury.jpg\",\"datePublished\":\"2019-02-18T16:09:17+00:00\",\"dateModified\":\"2019-06-25T13:10:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/02\\\/Fotowettbewerb-Blog_Header_Jury.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/02\\\/Fotowettbewerb-Blog_Header_Jury.jpg\",\"width\":1048,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/compte-rebours-concours-photo-etudiant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/\",\"name\":\"Hahnem\u00fchle Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\",\"name\":\"Bettina Scheerbarth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"caption\":\"Bettina Scheerbarth\"},\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/author\\\/b_scheerbarth\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/","og_locale":"fr_FR","og_type":"article","og_title":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog","og_description":"[vc_row][vc_column][vc_column_text]Le tout premier concours photo \u00e9tudiant Hahnem\u00fchle d\u00e9marre tr\u00e8s bient\u00f4t, au mois de mars et nous commencerons par l&rsquo;\u00e9tape de soumissions des images. Vous en \u00eates ? Relevez le d\u00e9fi et rencontrez notre jury !\u00a0 A l&rsquo;occasion de notre concours photo \u00e9tudiant, nous avons r\u00e9uni un jury de renomm\u00e9e internationale qui \u00e9valuera vos photos d&rsquo;un&hellip;","og_url":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/","og_site_name":"Hahnem\u00fchle Blog","article_published_time":"2019-02-18T16:09:17+00:00","article_modified_time":"2019-06-25T13:10:16+00:00","og_image":[{"width":1048,"height":508,"url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","type":"image\/jpeg"}],"author":"Bettina Scheerbarth","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bettina Scheerbarth","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#article","isPartOf":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/"},"author":{"name":"Bettina Scheerbarth","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626"},"headline":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 !","datePublished":"2019-02-18T16:09:17+00:00","dateModified":"2019-06-25T13:10:16+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/"},"wordCount":1482,"commentCount":0,"image":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","keywords":["concours photo \u00e9tudiant"],"articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/","url":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/","name":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 ! - Hahnem\u00fchle Blog","isPartOf":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#primaryimage"},"image":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","datePublished":"2019-02-18T16:09:17+00:00","dateModified":"2019-06-25T13:10:16+00:00","author":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626"},"breadcrumb":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#primaryimage","url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","contentUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","width":1048,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hahnemuehle.com\/fr\/compte-rebours-concours-photo-etudiant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.hahnemuehle.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le compte \u00e0 rebours du Concours Photo Etudiant a commenc\u00e9 !"}]},{"@type":"WebSite","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#website","url":"https:\/\/blog.hahnemuehle.com\/fr\/","name":"Hahnem\u00fchle Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hahnemuehle.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626","name":"Bettina Scheerbarth","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","caption":"Bettina Scheerbarth"},"url":"https:\/\/blog.hahnemuehle.com\/fr\/author\/b_scheerbarth\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2019\/02\/Fotowettbewerb-Blog_Header_Jury.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7Mut2-4rf","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts\/17065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/comments?post=17065"}],"version-history":[{"count":13,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts\/17065\/revisions"}],"predecessor-version":[{"id":17269,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts\/17065\/revisions\/17269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/media\/17106"}],"wp:attachment":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/media?parent=17065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/categories?post=17065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/tags?post=17065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}