{"id":8560,"date":"2015-10-16T08:00:13","date_gmt":"2015-10-16T06:00:13","guid":{"rendered":"http:\/\/news.hahnemuehle.com\/?p=8560"},"modified":"2015-10-16T08:00:13","modified_gmt":"2015-10-16T06:00:13","slug":"youtangleart","status":"publish","type":"post","link":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/","title":{"rendered":"Devenez accro au gribouillage sur papier Hahnem\u00fchle!"},"content":{"rendered":"<p>Tracez vous un chemin vers la paix et la s\u00e9r\u00e9nit\u00e9 avec nos cartes YouTangle.art! Pour vos inspirations cr\u00e9atives, Hahnem\u00fchle propose maintenant les Tangle Cards, &#8211; ou Tuiles! &#8211; dans une petite bo\u00eete de m\u00e9tal tr\u00e8s styl\u00e9e. Chaque bo\u00eete contient 25 cartes d&rsquo;un papier parfait pour les dessins de vos moments de r\u00e9flexions et de vos envies de style. Les tuiles carr\u00e9es, aux coins arrondis, se pr\u00eatent id\u00e9alement aux lignes fluides et pr\u00e9cises des feutres et crayons, mais sont aussi tr\u00e8s bien adapt\u00e9es aux crayons de couleur, stylos \u00e0 encre et marqueurs.<\/p>\n<p>Les cartes, de 9&#215;9 cm, sont pr\u00e9sent\u00e9es dans une bo\u00eete de m\u00e9tal con\u00e7ue pour les conserver au mieux et qui tient dans la main. Les cartes &#8211; vierges ou utilis\u00e9es- sont ainsi parfaitement transportables comme dans une petite bo\u00eete aux tr\u00e9sors. Avec YouTangle.art, vous pouvez dessiner partout et quand vous le souhaitez avec quelques crayons <!--more--><br \/>\n<a href=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/\u00a9Matthias-Hennig_Tangle-Tile-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-8597\" src=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/\u00a9Matthias-Hennig_Tangle-Tile-6-295x300.jpg\" alt=\"\u00a9Matthias Hennig_Tangle Tile 6\" width=\"213\" height=\"217\" \/><\/a>Nous avons demand\u00e9 aux artistes \u00a0<a href=\"http:\/\/www.virginiaromo.com\/\" target=\"_blank\">Virginia Romo<\/a> et <a href=\"http:\/\/www.hennig-design.de\" target=\"_blank\">Matthias Hennig<\/a> de tester nos nouvelles cartes YouTangle.art. La premi\u00e8re conclusion de l&rsquo;artiste illustratrice<a href=\"http:\/\/www.virginiaromo.com\/\" target=\"_blank\">Virginia Romo<\/a> r\u00e9sume tout: \u00ab\u00a0Attention, on devient vite accroc aux cartes <span id=\"result_box\" lang=\"en\"><a href=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-as-gift-tag.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8576\" src=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-as-gift-tag-300x196.jpg\" alt=\"YouTangle.art as gift tag\" width=\"254\" height=\"166\" \/><\/a><\/span>YouTangle.art de Hahnem\u00fchle! J&rsquo;aime les motifs floraux et folkloriques, et je me sers souvent de ces cartes comme etiquettes cadeaux. Je les ai test\u00e9es avec diff\u00e9rents crayons, &#8211; pointe fine, marqueurs, feutres, ou m\u00eame des stylos billes- et tout marche \u00e0 merveille, les couleurs ne bavent pas, ne tachent pas et sechent tres vite. C&rsquo;est tr\u00e8s agr\u00e9able de dessiner sur des cartes YouTangle.art \u00a0\u00bb<\/p>\n<p>To tangle, gribouiller en anglais, signifie dessiner des motifs faciles, abstraits, encore et encore. La r\u00e9p\u00e9tition contient tout l&rsquo;aspect m\u00e9ditatif de cette pratique artistique. Et artistique ne signifie pas que c&rsquo;est r\u00e9serv\u00e9 aux personnes dites cr\u00e9atives. Tout le monde gribouille!! \u00a0 <span id=\"result_box\" lang=\"en\">Le smotifs \u00e0 gribouiller sont des \u00e9l\u00e9ments qui se r\u00e9p\u00e8tent sans forc\u00e9ment \u00eatre parfaits, ce qui leur donne cet aspect vivant et irr\u00e9gulier. <\/span><\/p>\n<p>Le dessin d&rsquo;origine peut se trouver dehors, ou \u00e9maner de votre imagination! Ls souvenirs d&rsquo;un motif floral, ou la vue des pav\u00e9s dans le jardin peuvent aussi donner de grandes id\u00e9es! Ces motifs viennent du contratse noir et blanc, des colorisations modestes. Pour gribouiller, rien ne vaut la maxime \u00a0\u00bb ce qui passe par la main passe par la t\u00eate\u00a0\u00bb. La r\u00e9p\u00e9tition des motifs dessin\u00e9s entra\u00eene une relaxation holistique, qui est comme un \u00ab\u00a0courant\u00a0\u00bb : faire sans r\u00e9fl\u00e9chir, mesurer et pr\u00e9voir le r\u00e9sutat, voil\u00e0 la force de la m\u00e9ditation. Le gribouillage devient intuitif, une fois que vous avez commenc\u00e9.<a href=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/\u00a9Matthias-Hennig_Tangle-Tile-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8574 \" src=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/\u00a9Matthias-Hennig_Tangle-Tile-4-297x300.jpg\" alt=\"\u00a9Matthias Hennig_Tangle Tile 4\" width=\"210\" height=\"213\" \/><\/a><\/p>\n<p>Les tuiles YouTangle.art de Hahnem\u00fchle sont de eptites invitations \u00e0 dessiner. Leur taille est r\u00e9duite, elles sont parfaites pour finir m\u00eame une oeuvre d&rsquo;art dans un temps imparti. Le designer \u00a0<a href=\"http:\/\/www.hennig-design.de\" target=\"_blank\">Matthias Hennig<\/a>est une \u00ab\u00a0expert en motifs\u00a0\u00bb et donc poru nous le parfait testeur de YouTangle-art: \u00ab\u00a0Le format des cartes et merveilleux, tr\u00e8s maniable. Gr\u00e2ce aux coins arrondis, il y a peu de risques de former les fameuses oreilles d&rsquo;\u00e2ne \u00e9corn\u00e9es, qui sont le r\u00e9sultats de plusieurs manipulations. M\u00eame sans encadrement, elles font de beaux objets finis. Pour moi, elle ssont id\u00e9ales pour les dessins abstraits ou fantaisie.\u00a0\u00bb<\/p>\n<p><a href=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-8635\" src=\"http:\/\/blog.hahnemuehle.com\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles-300x290.jpg\" alt=\"YouTangle.art Box and Tiles\" width=\"300\" height=\"290\" srcset=\"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles-300x290.jpg 300w, https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles-1024x990.jpg 1024w, https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles-500x484.jpg 500w, https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/YouTangle.art-Box-and-Tiles.jpg 1832w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Les cartes YouTangle.art cards sont maintenant disponibles aupr\u00e8s de votre d\u00e9taillant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tracez vous un chemin vers la paix et la s\u00e9r\u00e9nit\u00e9 avec nos cartes YouTangle.art! Pour vos inspirations cr\u00e9atives, Hahnem\u00fchle propose maintenant les Tangle Cards, &#8211; ou Tuiles! &#8211; dans une petite bo\u00eete de m\u00e9tal tr\u00e8s styl\u00e9e. Chaque bo\u00eete contient 25 cartes d&rsquo;un papier parfait pour les dessins de vos moments de r\u00e9flexions et de vos&hellip;<\/p>\n","protected":false},"author":9,"featured_media":8573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1919,1947],"tags":[2088,2704,2705,2708,2709,2711,2712,2713,2714],"class_list":["post-8560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-papiers-beaux-arts","tag-illustration","tag-mandala","tag-matthias-hennig","tag-tangle-tiles","tag-tangleart","tag-tanglen","tag-tanglepapier","tag-virginia-romo","tag-youtangle-art","category-1919","category-1947","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog\" \/>\n<meta property=\"og:description\" content=\"Tracez vous un chemin vers la paix et la s\u00e9r\u00e9nit\u00e9 avec nos cartes YouTangle.art! Pour vos inspirations cr\u00e9atives, Hahnem\u00fchle propose maintenant les Tangle Cards, &#8211; ou Tuiles! &#8211; dans une petite bo\u00eete de m\u00e9tal tr\u00e8s styl\u00e9e. Chaque bo\u00eete contient 25 cartes d&rsquo;un papier parfait pour les dessins de vos moments de r\u00e9flexions et de vos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/\" \/>\n<meta property=\"og:site_name\" content=\"Hahnem\u00fchle Blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-16T06:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5436\" \/>\n\t<meta property=\"og:image:height\" content=\"2914\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bettina Scheerbarth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bettina Scheerbarth\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/\"},\"author\":{\"name\":\"Bettina Scheerbarth\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\"},\"headline\":\"Devenez accro au gribouillage sur papier Hahnem\u00fchle!\",\"datePublished\":\"2015-10-16T06:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/\"},\"wordCount\":594,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/10\\\/Hahnemuehle_You_Tangle_art_01.jpg\",\"keywords\":[\"illustration\",\"Mandala\",\"Matthias Hennig\",\"Tangle Tiles\",\"TangleArt\",\"tanglen\",\"Tanglepapier\",\"Virginia Romo\",\"YouTangle.art\"],\"articleSection\":[\"Blog\",\"Papiers Beaux-Arts\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/\",\"name\":\"Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/10\\\/Hahnemuehle_You_Tangle_art_01.jpg\",\"datePublished\":\"2015-10-16T06:00:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/10\\\/Hahnemuehle_You_Tangle_art_01.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2015\\\/10\\\/Hahnemuehle_You_Tangle_art_01.jpg\",\"width\":5436,\"height\":2914},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/youtangleart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devenez accro au gribouillage sur papier Hahnem\u00fchle!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/\",\"name\":\"Hahnem\u00fchle Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/#\\\/schema\\\/person\\\/72521995229af8408f85fa002e8f3626\",\"name\":\"Bettina Scheerbarth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g\",\"caption\":\"Bettina Scheerbarth\"},\"url\":\"https:\\\/\\\/blog.hahnemuehle.com\\\/fr\\\/author\\\/b_scheerbarth\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/","og_locale":"fr_FR","og_type":"article","og_title":"Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog","og_description":"Tracez vous un chemin vers la paix et la s\u00e9r\u00e9nit\u00e9 avec nos cartes YouTangle.art! Pour vos inspirations cr\u00e9atives, Hahnem\u00fchle propose maintenant les Tangle Cards, &#8211; ou Tuiles! &#8211; dans une petite bo\u00eete de m\u00e9tal tr\u00e8s styl\u00e9e. Chaque bo\u00eete contient 25 cartes d&rsquo;un papier parfait pour les dessins de vos moments de r\u00e9flexions et de vos&hellip;","og_url":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/","og_site_name":"Hahnem\u00fchle Blog","article_published_time":"2015-10-16T06:00:13+00:00","og_image":[{"width":5436,"height":2914,"url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","type":"image\/jpeg"}],"author":"Bettina Scheerbarth","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bettina Scheerbarth","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#article","isPartOf":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/"},"author":{"name":"Bettina Scheerbarth","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626"},"headline":"Devenez accro au gribouillage sur papier Hahnem\u00fchle!","datePublished":"2015-10-16T06:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/"},"wordCount":594,"commentCount":0,"image":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","keywords":["illustration","Mandala","Matthias Hennig","Tangle Tiles","TangleArt","tanglen","Tanglepapier","Virginia Romo","YouTangle.art"],"articleSection":["Blog","Papiers Beaux-Arts"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/","url":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/","name":"Devenez accro au gribouillage sur papier Hahnem\u00fchle! - Hahnem\u00fchle Blog","isPartOf":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#primaryimage"},"image":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","datePublished":"2015-10-16T06:00:13+00:00","author":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626"},"breadcrumb":{"@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#primaryimage","url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","contentUrl":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","width":5436,"height":2914},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hahnemuehle.com\/fr\/youtangleart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.hahnemuehle.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Devenez accro au gribouillage sur papier Hahnem\u00fchle!"}]},{"@type":"WebSite","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#website","url":"https:\/\/blog.hahnemuehle.com\/fr\/","name":"Hahnem\u00fchle Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hahnemuehle.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.hahnemuehle.com\/fr\/#\/schema\/person\/72521995229af8408f85fa002e8f3626","name":"Bettina Scheerbarth","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74531afc5c33660429ea7addff85487e31922849c774c51d41819929c5471e74?s=96&d=mm&r=g","caption":"Bettina Scheerbarth"},"url":"https:\/\/blog.hahnemuehle.com\/fr\/author\/b_scheerbarth\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.hahnemuehle.com\/fr\/wp-content\/uploads\/sites\/10\/2015\/10\/Hahnemuehle_You_Tangle_art_01.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7Mut2-2e4","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts\/8560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/comments?post=8560"}],"version-history":[{"count":0,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/posts\/8560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/media\/8573"}],"wp:attachment":[{"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/media?parent=8560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/categories?post=8560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hahnemuehle.com\/fr\/wp-json\/wp\/v2\/tags?post=8560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}